{"id":101413,"date":"2024-06-19T10:27:51","date_gmt":"2024-06-19T10:27:51","guid":{"rendered":"https:\/\/www.softswiss.com\/?p=101413"},"modified":"2024-08-19T10:28:24","modified_gmt":"2024-08-19T10:28:24","slug":"softswiss-wins-double-at-migea-2024","status":"publish","type":"post","link":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/","title":{"rendered":"SOFTSWISS ganha duas categorias no MiGEA 2024"},"content":{"rendered":"<?xml encoding=\"UTF-8\"><p><b>A SOFTSWISS ganhou os pr&ecirc;mios de Melhor Suporte de Atendimento ao Cliente e Melhor Provedor de Servi&ccedil;os de Criptomoedas no Malta's Gaming Excellence Awards 2024.<\/b><!--more--><\/p><p><span style=\"font-weight: 400;\">Devido &agrave; sua localiza&ccedil;&atilde;o em Malta, que abriga uma ampla gama de empresas de iGaming, o <\/span><b>Malta's Gaming Excellence Awards<\/b><span style=\"font-weight: 400;\"> se tornou um evento importante na ind&uacute;stria. Ele recompensa empresas e indiv&iacute;duos que constantemente inovam e melhoram o setor.<\/span><\/p><h2><span style=\"font-weight: 400;\">Melhor Provedor de Servi&ccedil;os de Cripto<\/span><\/h2><p><span style=\"font-weight: 400;\">A SOFTSWISS ganhou o pr&ecirc;mio de &ldquo;<\/span><b>Melhor Provedor de Servi&ccedil;os de Criptomoedas<\/b><span style=\"font-weight: 400;\">&rdquo; devido aos recursos abrangentes da sua <\/span><a href=\"https:\/\/www.softswiss.com\/pt\/crypto-casino-solution\/\"><b>Solu&ccedil;&atilde;o de Cassino de Cripto<\/b><\/a><span style=\"font-weight: 400;\">, incluindo gerenciamento de jogadores, bonifica&ccedil;&atilde;o, gamifica&ccedil;&atilde;o e relat&oacute;rios. A plataforma aceita as principais criptomoedas, incluindo Bitcoin, Ethereum, Litecoin, Dogecoin, Tether, entre outras. Ela oferece processamento de cripto seguro, consultoria extensa sobre jogos com criptomoedas e possibilidades de convers&atilde;o de moeda no jogo.<\/span><\/p><h2><span style=\"font-weight: 400;\">Melhor Suporte de Atendimento ao Cliente<\/span><\/h2><p><span style=\"font-weight: 400;\">O pr&ecirc;mio de '<\/span><b>Melhor Suporte de Atendimento ao Cliente<\/b><span style=\"font-weight: 400;\">' foi concedido &agrave; SOFTSWISS por suas not&aacute;veis conquistas na melhoria dos servi&ccedil;os aos clientes. No primeiro trimestre de 2024, a equipe de Anti-Fraude dos Servi&ccedil;os Gerenciados ajudou os clientes da SOFTSWISS a economizar 4,3 milh&otilde;es de euros. Uma das funcionalidades inovadoras implementadas pelos <\/span><b>Servi&ccedil;os Gerenciados<\/b><span style=\"font-weight: 400;\"> &eacute; uma ferramenta propriet&aacute;ria de Pontua&ccedil;&atilde;o de Risco de Jogo Respons&aacute;vel que detecta viola&ccedil;&otilde;es de jogo usando algoritmos de ML.<\/span><\/p><p><span style=\"font-weight: 400;\">O suporte de atendimento ao cliente da SOFTSWISS &eacute; fundamental para melhorar a experi&ecirc;ncia do usu&aacute;rio e identificar erros t&eacute;cnicos, aprimorando o desempenho financeiro dos clientes e fornecendo prote&ccedil;&atilde;o robusta contra fraudes.<\/span><\/p><p><span style=\"font-weight: 400;\">&ldquo;Este reconhecimento destaca o compromisso da SOFTSWISS em fornecer solu&ccedil;&otilde;es premiadas e experi&ecirc;ncias excepcionais aos seus parceiros. Estamos orgulhosos de ser reconhecidos pelo MiGEA como l&iacute;deres em solu&ccedil;&otilde;es de cripto e suportede atendimento ao cliente. Nossa empresa gostaria de agradecer aos organizadores, jurados e parceiros por tornar essa conquista poss&iacute;vel.&rdquo;<\/span><\/p><p><b>Vitali Matsukevich<\/b> <b>Diretor de Opera&ccedil;&otilde;es SOFTSWISS<\/b><\/p><p><span style=\"font-weight: 400;\">Nos dias 17 e 18 de julho, a SOFTSWISS participar&aacute; da <\/span><b>iGB L!VE<\/b><span style=\"font-weight: 400;\"> em Amsterd&atilde;. Atrav&eacute;s do link, parceiros e potenciais clientes podem agendar uma reuni&atilde;o com as equipes premiadas da SOFTSWISS no estande 12-F30 para explorar seu ecossistema de produtos de iGaming e discutir oportunidades de parceria.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":49,"featured_media":95548,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"limit_modified_date":"1","last_modified_date":"","ep_exclude_from_search":false,"footnotes":""},"categories":[237,236],"tags":[],"class_list":["post-101413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SOFTSWISS ganha duas categorias no MiGEA 2024 | SOFTSWISS<\/title>\n<meta name=\"description\" content=\"O SOFTSWISS ganhou os pr\u00eamios \u201cMelhor suporte de atendimento ao cliente\u201d e \u201cMelhor provedor de servi\u00e7os de criptografia\u201d no Gaming Excellence Awards 2024 de Malta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SOFTSWISS ganha duas categorias no MiGEA 2024 | SOFTSWISS\" \/>\n<meta property=\"og:description\" content=\"O SOFTSWISS ganhou os pr\u00eamios \u201cMelhor suporte de atendimento ao cliente\u201d e \u201cMelhor provedor de servi\u00e7os de criptografia\u201d no Gaming Excellence Awards 2024 de Malta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"SOFTSWISS\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-19T10:27:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-19T10:28:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.softswiss.com\/wp-content\/uploads\/2024\/06\/Softswiss_Award_1200x627_text-1024x535.webp\" \/>\n<meta name=\"author\" content=\"Volha Halota\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.softswiss.com\/wp-content\/uploads\/2024\/06\/Softswiss_Award_1200x627_text-1024x535.webp\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Volha Halota\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/news\\\/softswiss-wins-double-at-migea-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/news\\\/softswiss-wins-double-at-migea-2024\\\/\"},\"author\":{\"name\":\"Volha Halota\",\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/#\\\/schema\\\/person\\\/fabe4f9322c594a9b61d42300359b8fa\"},\"headline\":\"SOFTSWISS ganha duas categorias no MiGEA 2024\",\"datePublished\":\"2024-06-19T10:27:51+00:00\",\"dateModified\":\"2024-08-19T10:28:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/news\\\/softswiss-wins-double-at-migea-2024\\\/\"},\"wordCount\":386,\"publisher\":{\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/news\\\/softswiss-wins-double-at-migea-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.softswiss.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Softswiss_Award_1200x627_no_text.webp\",\"articleSection\":[\"Comunica\u00e7\u00f5es\",\"Not\u00edcias\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/news\\\/softswiss-wins-double-at-migea-2024\\\/\",\"url\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/news\\\/softswiss-wins-double-at-migea-2024\\\/\",\"name\":\"SOFTSWISS ganha duas categorias no MiGEA 2024 | SOFTSWISS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/news\\\/softswiss-wins-double-at-migea-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/news\\\/softswiss-wins-double-at-migea-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.softswiss.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Softswiss_Award_1200x627_no_text.webp\",\"datePublished\":\"2024-06-19T10:27:51+00:00\",\"dateModified\":\"2024-08-19T10:28:24+00:00\",\"description\":\"O SOFTSWISS ganhou os pr\u00eamios \u201cMelhor suporte de atendimento ao cliente\u201d e \u201cMelhor provedor de servi\u00e7os de criptografia\u201d no Gaming Excellence Awards 2024 de Malta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/news\\\/softswiss-wins-double-at-migea-2024\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/news\\\/softswiss-wins-double-at-migea-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/news\\\/softswiss-wins-double-at-migea-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.softswiss.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Softswiss_Award_1200x627_no_text.webp\",\"contentUrl\":\"https:\\\/\\\/www.softswiss.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Softswiss_Award_1200x627_no_text.webp\",\"width\":1200,\"height\":627,\"caption\":\"MiGEA_Award_2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/news\\\/softswiss-wins-double-at-migea-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SOFTSWISS ganha duas categorias no MiGEA 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/\",\"name\":\"SOFTSWISS\",\"description\":\"iGaming software provider\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/#organization\",\"name\":\"SOFTSWISS\",\"url\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.softswiss.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/softswiss-logo-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.softswiss.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/softswiss-logo-icon.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"SOFTSWISS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/#\\\/schema\\\/person\\\/fabe4f9322c594a9b61d42300359b8fa\",\"name\":\"Volha Halota\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/997919462d8e3145014514f7341b121abcfde7a5da4cb985ee572dce47aed402?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/997919462d8e3145014514f7341b121abcfde7a5da4cb985ee572dce47aed402?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/997919462d8e3145014514f7341b121abcfde7a5da4cb985ee572dce47aed402?s=96&d=mm&r=g\",\"caption\":\"Volha Halota\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/volha-halota-olga-golota-96b02282\\\/\"],\"url\":\"https:\\\/\\\/www.softswiss.com\\\/pt\\\/authors\\\/volha-halota\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SOFTSWISS ganha duas categorias no MiGEA 2024 | SOFTSWISS","description":"O SOFTSWISS ganhou os pr\u00eamios \u201cMelhor suporte de atendimento ao cliente\u201d e \u201cMelhor provedor de servi\u00e7os de criptografia\u201d no Gaming Excellence Awards 2024 de Malta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/","og_locale":"pt_PT","og_type":"article","og_title":"SOFTSWISS ganha duas categorias no MiGEA 2024 | SOFTSWISS","og_description":"O SOFTSWISS ganhou os pr\u00eamios \u201cMelhor suporte de atendimento ao cliente\u201d e \u201cMelhor provedor de servi\u00e7os de criptografia\u201d no Gaming Excellence Awards 2024 de Malta.","og_url":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/","og_site_name":"SOFTSWISS","article_published_time":"2024-06-19T10:27:51+00:00","article_modified_time":"2024-08-19T10:28:24+00:00","og_image":[{"url":"https:\/\/www.softswiss.com\/wp-content\/uploads\/2024\/06\/Softswiss_Award_1200x627_text-1024x535.webp","type":"","width":"","height":""}],"author":"Volha Halota","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.softswiss.com\/wp-content\/uploads\/2024\/06\/Softswiss_Award_1200x627_text-1024x535.webp","twitter_misc":{"Written by":"Volha Halota","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/#article","isPartOf":{"@id":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/"},"author":{"name":"Volha Halota","@id":"https:\/\/www.softswiss.com\/pt\/#\/schema\/person\/fabe4f9322c594a9b61d42300359b8fa"},"headline":"SOFTSWISS ganha duas categorias no MiGEA 2024","datePublished":"2024-06-19T10:27:51+00:00","dateModified":"2024-08-19T10:28:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/"},"wordCount":386,"publisher":{"@id":"https:\/\/www.softswiss.com\/pt\/#organization"},"image":{"@id":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.softswiss.com\/wp-content\/uploads\/2024\/06\/Softswiss_Award_1200x627_no_text.webp","articleSection":["Comunica\u00e7\u00f5es","Not\u00edcias"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/","url":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/","name":"SOFTSWISS ganha duas categorias no MiGEA 2024 | SOFTSWISS","isPartOf":{"@id":"https:\/\/www.softswiss.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.softswiss.com\/wp-content\/uploads\/2024\/06\/Softswiss_Award_1200x627_no_text.webp","datePublished":"2024-06-19T10:27:51+00:00","dateModified":"2024-08-19T10:28:24+00:00","description":"O SOFTSWISS ganhou os pr\u00eamios \u201cMelhor suporte de atendimento ao cliente\u201d e \u201cMelhor provedor de servi\u00e7os de criptografia\u201d no Gaming Excellence Awards 2024 de Malta.","breadcrumb":{"@id":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/#primaryimage","url":"https:\/\/www.softswiss.com\/wp-content\/uploads\/2024\/06\/Softswiss_Award_1200x627_no_text.webp","contentUrl":"https:\/\/www.softswiss.com\/wp-content\/uploads\/2024\/06\/Softswiss_Award_1200x627_no_text.webp","width":1200,"height":627,"caption":"MiGEA_Award_2"},{"@type":"BreadcrumbList","@id":"https:\/\/www.softswiss.com\/pt\/news\/softswiss-wins-double-at-migea-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.softswiss.com\/pt\/"},{"@type":"ListItem","position":2,"name":"SOFTSWISS ganha duas categorias no MiGEA 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.softswiss.com\/pt\/#website","url":"https:\/\/www.softswiss.com\/pt\/","name":"SOFTSWISS","description":"iGaming software provider","publisher":{"@id":"https:\/\/www.softswiss.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.softswiss.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.softswiss.com\/pt\/#organization","name":"SOFTSWISS","url":"https:\/\/www.softswiss.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.softswiss.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/www.softswiss.com\/wp-content\/uploads\/2022\/04\/softswiss-logo-icon.jpg","contentUrl":"https:\/\/www.softswiss.com\/wp-content\/uploads\/2022\/04\/softswiss-logo-icon.jpg","width":1024,"height":1024,"caption":"SOFTSWISS"},"image":{"@id":"https:\/\/www.softswiss.com\/pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.softswiss.com\/pt\/#\/schema\/person\/fabe4f9322c594a9b61d42300359b8fa","name":"Volha Halota","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/997919462d8e3145014514f7341b121abcfde7a5da4cb985ee572dce47aed402?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/997919462d8e3145014514f7341b121abcfde7a5da4cb985ee572dce47aed402?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/997919462d8e3145014514f7341b121abcfde7a5da4cb985ee572dce47aed402?s=96&d=mm&r=g","caption":"Volha Halota"},"sameAs":["https:\/\/www.linkedin.com\/in\/volha-halota-olga-golota-96b02282\/"],"url":"https:\/\/www.softswiss.com\/pt\/authors\/volha-halota\/"}]}},"fimg_url":"https:\/\/www.softswiss.com\/wp-content\/uploads\/2024\/06\/Softswiss_Award_1200x627_no_text.webp","_links":{"self":[{"href":"https:\/\/www.softswiss.com\/pt\/wp-json\/wp\/v2\/posts\/101413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.softswiss.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.softswiss.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.softswiss.com\/pt\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.softswiss.com\/pt\/wp-json\/wp\/v2\/comments?post=101413"}],"version-history":[{"count":2,"href":"https:\/\/www.softswiss.com\/pt\/wp-json\/wp\/v2\/posts\/101413\/revisions"}],"predecessor-version":[{"id":331791,"href":"https:\/\/www.softswiss.com\/pt\/wp-json\/wp\/v2\/posts\/101413\/revisions\/331791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.softswiss.com\/pt\/wp-json\/wp\/v2\/media\/95548"}],"wp:attachment":[{"href":"https:\/\/www.softswiss.com\/pt\/wp-json\/wp\/v2\/media?parent=101413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.softswiss.com\/pt\/wp-json\/wp\/v2\/categories?post=101413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.softswiss.com\/pt\/wp-json\/wp\/v2\/tags?post=101413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}